{"id":1131,"date":"2020-09-30T11:20:00","date_gmt":"2020-09-30T10:20:00","guid":{"rendered":"https:\/\/cpi-geneva.org\/fr\/2020\/09\/30\/the-cordoba-update-juillet-septembre-2020\/"},"modified":"2020-09-30T11:20:00","modified_gmt":"2020-09-30T10:20:00","slug":"the-cordoba-update-juillet-septembre-2020","status":"publish","type":"post","link":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/","title":{"rendered":"The Cordoba Update, juillet &#8211; septembre 2020"},"content":{"rendered":"<style scoped=\"scoped\" type=\"text\/css\"><!--\narticle .article-content div.left > p {text-align: left;}\n@media only screen and (min-width: 721px) {\n.cu_date {font-size: 24px; color: #aa9788; position: relative; float: right; top: -40px; right: 16px; margin-bottom: -40px;}\n.cu_lang-btn {max-width: 800px; margin: -38px 0 0 0; position: relative; bottom: -38px; right: 4px;}\n}\n@media only screen and (max-width: 720px) {\n.cu_date {font-size: 16px; color: #aa9788;}\n.cu_lang-btn {max-width: 800px;}\n.cu_lang-btn .docDownload_lang {padding: 2px 6px; margin: 3px 2px 3px 0; line-height: 1.0em;}\n.cu_lang-btn .docDownload_lang a {font-size: 70%;}\n}\n--><\/style>\n<p><!-- RIGHT --><\/p>\n<div class=\"cu_lang-btn\">\n<div class=\"docDownload_lang\"><a href=\"ar\/\u0645\u0646\u0634\u0648\u0631\u0627\u062a\/newsletter\/923\" class=\"arabTxt\">\u0627\u0644\u0646\u0633\u062e\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/a><\/div>\n<div class=\"docDownload_lang\"><a href=\"en\/publications-mega\/newsletter\/917\">English Version<\/a><\/div>\n<div class=\"clearfix\">&nbsp;<\/div>\n<\/div>\n<div style=\"max-width: 800px; margin: 0 0 15px 0;\"><img decoding=\"async\" class=\" size-full wp-image-774\" src=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2017\/10\/header_cu_blank.jpg\" alt=\"alt_text\" width=\"800\" height=\"auto\" style=\"width: 100%; max-width: 800px; height: auto; margin: 0;\" align=\"middle\" border=\"0\" srcset=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2017\/10\/header_cu_blank.jpg 1360w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2017\/10\/header_cu_blank-1024x226.jpg 1024w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2017\/10\/header_cu_blank-768x169.jpg 768w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<div class=\"cu_date\">Juillet &#8211; Septembre 2020<\/div>\n<\/div>\n<div class=\"left\" style=\"clear: left; float: left; display: inline-block; margin: auto 15px 15px auto; max-width: 265px; min-width: 160px; vertical-align: top; width: 100%; background-color: #993333; color: #ffffff; padding: 15px 20px 5px; font-size: 78%; line-height: 145%;\">\n<p>Cher Lecteur, Ch&egrave;re Lectrice,<\/p>\n<p>L&rsquo;explosion qui a d&eacute;vast&eacute; le centre de Beyrouth le 4 ao&ucirc;t dernier a abouti &agrave; l&rsquo;aggravation de la crise &eacute;conomique, sociale et environnementale au Liban et a mis en exergue des ann&eacute;es de responsabilit&eacute;s politiques n&eacute;glig&eacute;es. Cela fait plus d&rsquo;une d&eacute;cennie que de grandes quantit&eacute;s de d&eacute;chets se sont accumul&eacute;es &agrave; Beyrouth, provoquant de graves probl&egrave;mes sanitaires et environnementaux, en raison de l&rsquo;incapacit&eacute; des politiciens &agrave; convenir de solutions pour leur &eacute;limination en toute s&eacute;curit&eacute;. Les plaintes pour corruption end&eacute;mique n&rsquo;ont cess&eacute; de cro&icirc;tre au cours des derni&egrave;res ann&eacute;es, au sein d&rsquo;une population frustr&eacute;e par la d&eacute;t&eacute;rioration des conditions de vie, tandis que la nature sectaire de la politique libanaise emp&ecirc;che toute solution collaborative et coh&eacute;rente aux probl&egrave;mes pos&eacute;s au pays.<\/p>\n<p>Ces derni&egrave;res ann&eacute;es, CPI a lanc&eacute; des projets conjoints entre des acteurs humanitaires de la soci&eacute;t&eacute; libanaise, de diverses appartenances. Nous avons appris de ces exp&eacute;riences que la coop&eacute;ration pratique conduit &agrave; une plus grande compr&eacute;hension et un meilleur engagement entre les diverses composantes de la soci&eacute;t&eacute; &ndash; y compris en r&eacute;unissant les jeunes qui sont la cl&eacute; d&rsquo;un avenir meilleur et qui critiquent de plus en plus l&rsquo;&eacute;lite politique libanaise. Le dialogue qui &eacute;merge de la collaboration en vue d&rsquo;un objectif commun n&eacute;goci&eacute; dissipe les soup&ccedil;ons end&eacute;miques envers &laquo; l&rsquo;autre &raquo;. Pour le peuple et les leaders libanais, nous esp&eacute;rons sinc&egrave;rement que cette crise d&eacute;bouchera sur de plus grandes opportunit&eacute;s de dialogue, de projets communs et d&rsquo;inclusion de toutes les composantes de la soci&eacute;t&eacute;, trouvant ensemble la meilleure voie &agrave; suivre.<\/p>\n<p>Dans cette &eacute;dition de notre lettre d&rsquo;information, vous trouverez une premi&egrave;re contribution de notre partenaire local au Nig&eacute;ria, le centre Dar al-Andalus, faisant &eacute;tat d&rsquo;un atelier de formation organis&eacute; &agrave; Maiduguri au d&eacute;but de septembre. La deuxi&egrave;me contribution porte sur la comm&eacute;moration du 13e anniversaire du d&eacute;c&egrave;s de Cheikh Mahmoud Bouzouzou (portant des lunettes au milieu de l&rsquo;image), qui &eacute;tait membre du Conseil de CPI de 2002 &agrave; 2007.<\/p>\n<p>L&rsquo;&eacute;quipe CPI<\/p>\n<\/div>\n<div style=\"display: inline-block; margin: 0; max-width: 520px; min-width: 320px; vertical-align: top;\"><img decoding=\"async\" class=\" size-full wp-image-1124\" src=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg\" alt=\"CPI Board of Trustees, 2004\" width=\"680\" height=\"auto\" style=\"width: 100%; max-width: 680px; height: auto; background: #dddddd none repeat scroll 0% 0%; font-family: sans-serif; font-size: 14px; line-height: 16px; color: #555555; margin-top: auto; margin-bottom: 5px; vertical-align: middle;\" srcset=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg 926w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-768x475.jpg 768w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-640x396.jpg 640w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-400x248.jpg 400w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-367x227.jpg 367w\" sizes=\"(max-width: 926px) 100vw, 926px\" \/><\/p>\n<div style=\"background-color: #f4f1e8; margin-top: 0; padding: 5px 15px 7px; text-align: center;\"><span style=\"font-size: 84%;\"><em>R&eacute;union du Conseil de CPI, 25 juin 2004, &agrave; l&rsquo;occasion de <br \/>l&rsquo;organisation de la &laquo; Tente du Dialogue &raquo;, Parc Trembley, Gen&egrave;ve<\/em><\/span><\/div>\n<\/div>\n<div style=\"width: 100%; max-width: 800px; padding: 0px; text-align: left;\" align=\"center\">\n<h2 style=\"margin-bottom: 0px;\">Nouvelles de l&rsquo;Institut<\/h2>\n<hr style=\"margin-top: 0px; margin-bottom: 21px; border-top: 1px solid #dddddd;\" \/><\/div>\n<div style=\"width: 100%; max-width: 800px; padding: 0px 25px 0px 25px; text-align: left;\" align=\"center\">\n<p><strong>Nig&eacute;ria <\/strong>&#8211; En septembre, le partenaire de CPI au Nig&eacute;ria, le centre Dar al-Andalus, a organis&eacute; un atelier de deux jours pour les journalistes &agrave; Maiduguri, Etat de Borno. Plus de 40 journalistes ont particip&eacute;, de la t&eacute;l&eacute;vision, de la radio et de la presse &eacute;crite, ainsi que des blogueurs et des influenceurs des m&eacute;dias sociaux. L&rsquo;atelier a g&eacute;n&eacute;r&eacute; de nombreux apprentissages et beaucoup d&rsquo;enthousiasme quant &agrave; la mani&egrave;re dont un journalisme &eacute;thique et responsable dans des circonstances difficiles peut contribuer &agrave; la paix. L&rsquo;atelier a &eacute;t&eacute; per&ccedil;u comme hautement pertinent. Plus de d&eacute;tails sont donn&eacute;s dans le premier article ci-dessous, une contribution du centre Dar al-Andalus, avec une introduction du Dr Bala Muhammad.<\/p>\n<p><strong>Zanzibar <\/strong>&#8211; En juillet, CPI et son partenaire tanzanien Friends of Zanzibar, ont organis&eacute; six sessions de formation d&rsquo;une journ&eacute;e chacune sur le dialogue entre multiples parties prenantes pour sept leaders de la communaut&eacute; de Zanzibar, sur la m&eacute;diation pour deux groupes de 35 &eacute;tudiants et 30 leaders de jeunes repr&eacute;sentant 10 universit&eacute;s et 17 ONG. Une session de formation sur les m&eacute;canismes d&rsquo;alerte pr&eacute;coce et de r&eacute;ponse rapide &agrave; base communautaire a &eacute;t&eacute; donn&eacute;e &agrave; 26 acteurs communautaires de Pemba. En outre, une session de formation sur le journalisme de la paix a &eacute;t&eacute; dispens&eacute;e &agrave; 34 journalistes d&rsquo;Unguja et 10 journalistes de Pemba Press Club. Toutes les formations ont &eacute;t&eacute; dispens&eacute;es en anglais et en kiswahili.<\/p>\n<p><strong>Nouakchott <\/strong>&#8211; CPI a obtenu le 11 ao&ucirc;t 2020 l&rsquo;accord du gouvernement mauritanien d&rsquo;&eacute;tablir son bureau r&eacute;gional pour les op&eacute;rations au Sahel et au Bassin du Lac Tchad &agrave; Nouakchott. Ce bureau coordonnera les programmes de l&rsquo;Institut dans ces r&eacute;gions.<\/p>\n<hr \/>\n<\/div>\n<div class=\"clearfix\">&nbsp;<\/div>\n<p><!-- THUMB LEFT 1  --- BEGIN --- --><\/p>\n<div style=\"display: inline-block; margin: 0 -2px; max-width: 240px; min-width: 160px; vertical-align: top; width: 100%;\">\n<table border=\"0\" style=\"width: 100%;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"padding: 0 10px 10px 10px;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-1125\" src=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020.jpg\" alt=\"DarAndalusCenter 092020\" width=\"678\" height=\"446\" class=\"center-on-narrow\" style=\"width: 100%; max-width: 320px; height: auto; background: #dddddd none repeat scroll 0% 0%; font-family: sans-serif; font-size: 15px; line-height: 20px; color: #555555;\" srcset=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020.jpg 678w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020-640x421.jpg 640w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020-400x263.jpg 400w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020-367x241.jpg 367w, https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/DarAndalusCenter_092020-560x367.jpg 560w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"stack-column\" style=\"display: inline-block; max-width: 560px; min-width: 320px; vertical-align: top;\">\n<table border=\"0\" style=\"width: 100%;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td>\n<h2>Journalisme de la paix au Nig&eacute;ria<\/h2>\n<p><!-- Button : BEGIN --><\/p>\n<table border=\"0\" class=\"center-on-narrow\" style=\"float: left;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"button-td\" style=\"border-radius: 3px; background: #993333; text-align: center;\"><a href=\"fr\/publications-fr\/contributions\/921\" target=\"_blank\" style=\"background: #993333; border: 5px solid #993333; font-size: 12px; line-height: 1.0; text-align: center; text-decoration: none; display: block; border-radius: 3px; font-weight: bold;\" rel=\"noopener\"> <span class=\"button-link\" style=\"color: #ffffff;\">&nbsp;&nbsp;&nbsp; Lire l&rsquo;article&nbsp;&nbsp;&nbsp;&nbsp;<\/span><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!-- Button : END --><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div style=\"margin-bottom: 15px;\">&nbsp;<\/div>\n<p><!-- THUMB LEFT 1 ---- END ---- \n-- THUMB LEFT 2 --- BEGIN --- --><\/p>\n<div style=\"display: inline-block; margin: 0 -2px; max-width: 240px; min-width: 160px; vertical-align: top; width: 100%;\">\n<table border=\"0\" style=\"width: 100%;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"padding: 0 10px 10px 10px;\"><img decoding=\"async\" class=\" size-full wp-image-1126\" src=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/BouzouzouBook_thumb.png\" alt=\"BouzouzouBook thumb\" width=\"600\" height=\"576\" class=\"center-on-narrow\" style=\"width: 100%; max-width: 320px; height: auto; background: transparent none repeat scroll 0% 0%; font-family: sans-serif; font-size: 15px; line-height: 20px; color: #555555;\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"stack-column\" style=\"display: inline-block; max-width: 560px; min-width: 320px; vertical-align: top;\">\n<table border=\"0\" style=\"width: 100%;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td>\n<h2>Cheikh Mahmoud Bouzouzou un homme de dialogue<\/h2>\n<h5>par <strong>Abbas Aroua<\/strong><\/h5>\n<p><!-- Button : BEGIN --><\/p>\n<table border=\"0\" class=\"center-on-narrow\" style=\"float: left;\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"button-td\" style=\"border-radius: 3px; background: #993333; text-align: center;\"><a href=\"fr\/publications-fr\/contributions\/922\" target=\"_blank\" style=\"background: #993333; border: 5px solid #993333; font-size: 12px; line-height: 1.0; text-align: center; text-decoration: none; display: block; border-radius: 3px; font-weight: bold;\" rel=\"noopener\"> <span class=\"button-link\" style=\"color: #ffffff;\">&nbsp;&nbsp;&nbsp; Lire l&rsquo;article&nbsp;&nbsp;&nbsp;&nbsp;<\/span><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!-- Button : END --><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div style=\"margin-bottom: 15px;\">&nbsp;<\/div>\n<p><!-- THUMB LEFT 2 ---- END  --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0646\u0633\u062e\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 English Version &nbsp; Juillet &#8211; Septembre 2020 Cher Lecteur, Ch&egrave;re Lectrice, L&rsquo;explosion qui a d&eacute;vast&eacute; le centre de Beyrouth le 4 ao&ucirc;t dernier a abouti &agrave; l&rsquo;aggravation de la crise &eacute;conomique, sociale et environnementale au Liban et a mis en exergue des ann&eacute;es de responsabilit&eacute;s politiques n&eacute;glig&eacute;es. Cela fait plus d&rsquo;une d&eacute;cennie que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"\u0627\u0644\u0646\u0633\u062e\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 English Version &nbsp; Juillet &#8211; Septembre 2020 Cher Lecteur, Ch&egrave;re Lectrice, L&rsquo;explosion qui a d&eacute;vast&eacute; le centre de Beyrouth le 4 ao&ucirc;t dernier a abouti &agrave; l&rsquo;aggravation de la crise &eacute;conomique, sociale et environnementale au Liban et a mis en exergue des ann&eacute;es de responsabilit&eacute;s politiques n&eacute;glig&eacute;es. Cela fait plus d&rsquo;une d&eacute;cennie que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Cordoba Peace Institute | Fran\u00e7ais\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-30T10:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"926\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00f2rdoba Geneva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00f2rdoba Geneva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/\"},\"author\":{\"name\":\"C\u00f2rdoba Geneva\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#\\\/schema\\\/person\\\/0a62f528ac130e856881b492b5ac7a83\"},\"headline\":\"The Cordoba Update, juillet &#8211; septembre 2020\",\"datePublished\":\"2020-09-30T10:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/CPI_Board-of-Trustees_2004.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/\",\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/\",\"name\":\"The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/CPI_Board-of-Trustees_2004.jpg\",\"datePublished\":\"2020-09-30T10:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/CPI_Board-of-Trustees_2004.jpg\",\"contentUrl\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/09\\\/CPI_Board-of-Trustees_2004.jpg\",\"width\":926,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/the-cordoba-update-juillet-septembre-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Cordoba Update, juillet &#8211; septembre 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/\",\"name\":\"Cordoba Peace Institute - Gen\u00e8ve CPI\",\"description\":\"CPI Gen\u00e8ve | 20 ans aux service de la paix\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#organization\",\"name\":\"Cordoba Peace Institute - Gen\u00e8ve CPI\",\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/CPI-Geneva.png\",\"contentUrl\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/CPI-Geneva.png\",\"width\":740,\"height\":740,\"caption\":\"Cordoba Peace Institute - Gen\u00e8ve CPI\"},\"image\":{\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/#\\\/schema\\\/person\\\/0a62f528ac130e856881b492b5ac7a83\",\"name\":\"C\u00f2rdoba Geneva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g\",\"caption\":\"C\u00f2rdoba Geneva\"},\"url\":\"https:\\\/\\\/cpi-geneva.org\\\/fr\\\/author\\\/corwebmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais","og_description":"\u0627\u0644\u0646\u0633\u062e\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 English Version &nbsp; Juillet &#8211; Septembre 2020 Cher Lecteur, Ch&egrave;re Lectrice, L&rsquo;explosion qui a d&eacute;vast&eacute; le centre de Beyrouth le 4 ao&ucirc;t dernier a abouti &agrave; l&rsquo;aggravation de la crise &eacute;conomique, sociale et environnementale au Liban et a mis en exergue des ann&eacute;es de responsabilit&eacute;s politiques n&eacute;glig&eacute;es. Cela fait plus d&rsquo;une d&eacute;cennie que [&hellip;]","og_url":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/","og_site_name":"Cordoba Peace Institute | Fran\u00e7ais","article_published_time":"2020-09-30T10:20:00+00:00","og_image":[{"width":926,"height":573,"url":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg","type":"image\/jpeg"}],"author":"C\u00f2rdoba Geneva","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"C\u00f2rdoba Geneva","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#article","isPartOf":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/"},"author":{"name":"C\u00f2rdoba Geneva","@id":"https:\/\/cpi-geneva.org\/fr\/#\/schema\/person\/0a62f528ac130e856881b492b5ac7a83"},"headline":"The Cordoba Update, juillet &#8211; septembre 2020","datePublished":"2020-09-30T10:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/cpi-geneva.org\/fr\/#organization"},"image":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg","articleSection":["Newsletter"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/","url":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/","name":"The Cordoba Update, juillet - septembre 2020 - Cordoba Peace Institute | Fran\u00e7ais","isPartOf":{"@id":"https:\/\/cpi-geneva.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#primaryimage"},"image":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg","datePublished":"2020-09-30T10:20:00+00:00","breadcrumb":{"@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#primaryimage","url":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg","contentUrl":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg","width":926,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/cpi-geneva.org\/fr\/the-cordoba-update-juillet-septembre-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpi-geneva.org\/fr\/"},{"@type":"ListItem","position":2,"name":"The Cordoba Update, juillet &#8211; septembre 2020"}]},{"@type":"WebSite","@id":"https:\/\/cpi-geneva.org\/fr\/#website","url":"https:\/\/cpi-geneva.org\/fr\/","name":"Cordoba Peace Institute - Gen\u00e8ve CPI","description":"CPI Gen\u00e8ve | 20 ans aux service de la paix","publisher":{"@id":"https:\/\/cpi-geneva.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpi-geneva.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cpi-geneva.org\/fr\/#organization","name":"Cordoba Peace Institute - Gen\u00e8ve CPI","url":"https:\/\/cpi-geneva.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cpi-geneva.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/12\/CPI-Geneva.png","contentUrl":"https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/12\/CPI-Geneva.png","width":740,"height":740,"caption":"Cordoba Peace Institute - Gen\u00e8ve CPI"},"image":{"@id":"https:\/\/cpi-geneva.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cpi-geneva.org\/fr\/#\/schema\/person\/0a62f528ac130e856881b492b5ac7a83","name":"C\u00f2rdoba Geneva","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf6a4ecb9e914acddd89e4c4cbc3c6fdccfd6614c26ec3023ce0173515d50eff?s=96&d=mm&r=g","caption":"C\u00f2rdoba Geneva"},"url":"https:\/\/cpi-geneva.org\/fr\/author\/corwebmaster\/"}]}},"featured_image_src":{"landsacpe":["https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-926x445.jpg",926,445,true],"list":["https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-463x348.jpg",463,348,true],"medium":["https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004-300x186.jpg",300,186,true],"full":["https:\/\/cpi-geneva.org\/fr\/wp-content\/uploads\/sites\/3\/2020\/09\/CPI_Board-of-Trustees_2004.jpg",926,573,false]},"_links":{"self":[{"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/posts\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/comments?post=1131"}],"version-history":[{"count":0,"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/posts\/1131\/revisions"}],"wp:attachment":[{"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/media?parent=1131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/categories?post=1131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpi-geneva.org\/fr\/wp-json\/wp\/v2\/tags?post=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}